{"id":21464,"date":"2021-10-19T15:01:18","date_gmt":"2021-10-19T13:01:18","guid":{"rendered":"https:\/\/orfeve.com\/?post_type=product&#038;p=21464"},"modified":"2026-03-05T08:56:41","modified_gmt":"2026-03-05T07:56:41","slug":"tafel-dunkle-schookolade-esterre-80-grenada","status":"publish","type":"product","link":"https:\/\/orfeve.com\/de\/shop\/noir-de-noir\/tafel-dunkle-schookolade-esterre-80-grenada\/","title":{"rendered":"L&#8217;Esterre 80 (Grenada) &#8211; Extrafeine Dunkle Schokolade"},"content":{"rendered":"\r\n<div>\r\n<p>Die Insel Grenada liegt 150 km n\u00f6rdlich von Venezuela und verf\u00fcgt \u00fcber ein aussergew\u00f6hnliches vulkanisches Terroir. Auf ihren fruchtbaren B\u00f6den bauen die Plantagenbesitzer die Bohnen an, aus denen unsere 80\u202f% dunkle Schokolade L\u2019Esterre 80 entsteht.<\/p>\r\n<\/div>\r\n\r\n\r\n\r\n<div>\r\n<p>Die Insel, bekannt f\u00fcr ihre Gew\u00fcrze, bietet einen reichen und fruchtbaren Boden, der diesem Kakao seine besondere Einzigartigkeit verleiht.<\/p>\r\n<\/div>\r\n\r\n\r\n\r\n<p>Das Domaine L&#8217;Esterre ist seit \u00fcber 70 Jahren im alleinigen Besitz der Familie Ramdhanny. Die Plantage befindet sich im Nordosten der Insel, am Fusse von mit Regenwald bedeckten H\u00fcgeln.<\/p>\r\n\r\n\r\n\r\n<p>Die Familie baut Kakao und Muskatnuss streng nach den Regeln des biologischen Landbaus und der nachhaltigen Agroforstwirtschaft an und bewahrt so den Reichtum und die Fruchtbarkeit des Bodens.<\/p>\r\n\r\n\r\n\r\n<div>\r\n<p>Die Plantagenbesitzer ernten die Bohnen zwischen November und April, fermentieren sie vor Ort 7 bis 8 Tage lang und trocknen sie anschlie\u00dfend 6 bis 7 Tage in der Sonne.<\/p>\r\n<\/div>\r\n<div>\r\n<p>Diese 80\u202f% dunkle Schokolade ist das Ergebnis eines beherrschten Bean-to-Bar-Handwerks, von der Bohne bis zur Tafel. Er entfaltet das volle Potenzial eines einzigartigen Terroirs, veredelt durch das Know-how von ORF\u00c8VE.<\/p>\r\n<\/div>\r\n\r\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p class=\"p1\">80 % dunkle Trinitario-Schokolade aus Grenada. Dieser aussergew\u00f6hnliche <em>Cru de Propri\u00e9t\u00e9<\/em> zeichnet sich durch seine cremige S\u00fcsse und zarte Aromen von Banane, Fr\u00fcchten und N\u00fcssen aus.<\/p>\n","protected":false},"featured_media":25623,"template":"","meta":[],"product_brand":[],"product_cat":[296],"product_tag":[534],"class_list":{"0":"post-21464","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-noir-de-noir","7":"product_tag-tafeln","9":"first","10":"instock","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Dunkle Schokolade 80 % - L&#039;Esterre 80 (Grenada) - Noir de Noir - ORF\u00c8VE Chocolat suisse bean-to-bar<\/title>\n<meta name=\"description\" content=\"Dunkle Schokolade 80\u202f% aus Grenada, signiert von ORF\u00c8VE. Eine zart schmelzende Bean-to-Bar-Tafel mit Aromen von Banane und Pekannuss auf einem schokoladigen Hintergrund.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/orfeve.com\/de\/shop\/noir-de-noir\/tafel-dunkle-schookolade-esterre-80-grenada\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L&#039;Esterre 80 (Grenada) - Extrafeine Dunkle Schokolade\" \/>\n<meta property=\"og:description\" content=\"Dunkle Schokolade 80\u202f% aus Grenada, signiert von ORF\u00c8VE. Eine zart schmelzende Bean-to-Bar-Tafel mit Aromen von Banane und Pekannuss auf einem schokoladigen Hintergrund.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/orfeve.com\/de\/shop\/noir-de-noir\/tafel-dunkle-schookolade-esterre-80-grenada\/\" \/>\n<meta property=\"og:site_name\" content=\"ORF\u00c8VE Chocolat suisse bean-to-bar\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/orfevechocolat\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-05T07:56:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/orfeve.com\/wp-content\/uploads\/2021\/10\/ORFEVE_Noir-de-Noir_chocolat_L-ESTERRE-80.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@orfeve_Chocolat\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/orfeve.com\\\/de\\\/shop\\\/noir-de-noir\\\/tafel-dunkle-schookolade-esterre-80-grenada\\\/\",\"url\":\"https:\\\/\\\/orfeve.com\\\/de\\\/shop\\\/noir-de-noir\\\/tafel-dunkle-schookolade-esterre-80-grenada\\\/\",\"name\":\"Dunkle Schokolade 80 % - L'Esterre 80 (Grenada) - Noir de Noir - ORF\u00c8VE Chocolat suisse bean-to-bar\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/orfeve.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/orfeve.com\\\/de\\\/shop\\\/noir-de-noir\\\/tafel-dunkle-schookolade-esterre-80-grenada\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/orfeve.com\\\/de\\\/shop\\\/noir-de-noir\\\/tafel-dunkle-schookolade-esterre-80-grenada\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/orfeve.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/ORFEVE_Noir-de-Noir_chocolat_L-ESTERRE-80.jpg\",\"datePublished\":\"2021-10-19T13:01:18+00:00\",\"dateModified\":\"2026-03-05T07:56:41+00:00\",\"description\":\"Dunkle Schokolade 80\u202f% aus Grenada, signiert von ORF\u00c8VE. Eine zart schmelzende Bean-to-Bar-Tafel mit Aromen von Banane und Pekannuss auf einem schokoladigen Hintergrund.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/orfeve.com\\\/de\\\/shop\\\/noir-de-noir\\\/tafel-dunkle-schookolade-esterre-80-grenada\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/orfeve.com\\\/de\\\/shop\\\/noir-de-noir\\\/tafel-dunkle-schookolade-esterre-80-grenada\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/orfeve.com\\\/de\\\/shop\\\/noir-de-noir\\\/tafel-dunkle-schookolade-esterre-80-grenada\\\/#primaryimage\",\"url\":\"https:\\\/\\\/orfeve.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/ORFEVE_Noir-de-Noir_chocolat_L-ESTERRE-80.jpg\",\"contentUrl\":\"https:\\\/\\\/orfeve.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/ORFEVE_Noir-de-Noir_chocolat_L-ESTERRE-80.jpg\",\"width\":900,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/orfeve.com\\\/de\\\/shop\\\/noir-de-noir\\\/tafel-dunkle-schookolade-esterre-80-grenada\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/orfeve.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/orfeve.com\\\/de\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"L&#8217;Esterre 80 (Grenada) &#8211; Extrafeine Dunkle Schokolade\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/orfeve.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/orfeve.com\\\/en\\\/\",\"name\":\"ORF\u00c8VE Chocolat suisse bean-to-bar\",\"description\":\"Manufacture Suisse de Cacao et Chocolat Bean to Bar\",\"publisher\":{\"@id\":\"https:\\\/\\\/orfeve.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/orfeve.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/orfeve.com\\\/en\\\/#organization\",\"name\":\"ORF\u00c8VE\",\"url\":\"https:\\\/\\\/orfeve.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/orfeve.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/orfeve.com\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Orfeve-Manufacture-Suisse-de-Cacao-et-Chocolat-logo.jpeg\",\"contentUrl\":\"https:\\\/\\\/orfeve.com\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Orfeve-Manufacture-Suisse-de-Cacao-et-Chocolat-logo.jpeg\",\"width\":427,\"height\":170,\"caption\":\"ORF\u00c8VE\"},\"image\":{\"@id\":\"https:\\\/\\\/orfeve.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/orfevechocolat\\\/\",\"https:\\\/\\\/x.com\\\/orfeve_Chocolat\",\"https:\\\/\\\/www.instagram.com\\\/orfeve_chocolat\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/orfeve\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Dunkle Schokolade 80 % - L'Esterre 80 (Grenada) - Noir de Noir - ORF\u00c8VE Chocolat suisse bean-to-bar","description":"Dunkle Schokolade 80\u202f% aus Grenada, signiert von ORF\u00c8VE. Eine zart schmelzende Bean-to-Bar-Tafel mit Aromen von Banane und Pekannuss auf einem schokoladigen Hintergrund.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/orfeve.com\/de\/shop\/noir-de-noir\/tafel-dunkle-schookolade-esterre-80-grenada\/","og_locale":"de_DE","og_type":"article","og_title":"L'Esterre 80 (Grenada) - Extrafeine Dunkle Schokolade","og_description":"Dunkle Schokolade 80\u202f% aus Grenada, signiert von ORF\u00c8VE. Eine zart schmelzende Bean-to-Bar-Tafel mit Aromen von Banane und Pekannuss auf einem schokoladigen Hintergrund.","og_url":"https:\/\/orfeve.com\/de\/shop\/noir-de-noir\/tafel-dunkle-schookolade-esterre-80-grenada\/","og_site_name":"ORF\u00c8VE Chocolat suisse bean-to-bar","article_publisher":"https:\/\/www.facebook.com\/orfevechocolat\/","article_modified_time":"2026-03-05T07:56:41+00:00","og_image":[{"width":900,"height":900,"url":"https:\/\/orfeve.com\/wp-content\/uploads\/2021\/10\/ORFEVE_Noir-de-Noir_chocolat_L-ESTERRE-80.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@orfeve_Chocolat","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/orfeve.com\/de\/shop\/noir-de-noir\/tafel-dunkle-schookolade-esterre-80-grenada\/","url":"https:\/\/orfeve.com\/de\/shop\/noir-de-noir\/tafel-dunkle-schookolade-esterre-80-grenada\/","name":"Dunkle Schokolade 80 % - L'Esterre 80 (Grenada) - Noir de Noir - ORF\u00c8VE Chocolat suisse bean-to-bar","isPartOf":{"@id":"https:\/\/orfeve.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/orfeve.com\/de\/shop\/noir-de-noir\/tafel-dunkle-schookolade-esterre-80-grenada\/#primaryimage"},"image":{"@id":"https:\/\/orfeve.com\/de\/shop\/noir-de-noir\/tafel-dunkle-schookolade-esterre-80-grenada\/#primaryimage"},"thumbnailUrl":"https:\/\/orfeve.com\/wp-content\/uploads\/2021\/10\/ORFEVE_Noir-de-Noir_chocolat_L-ESTERRE-80.jpg","datePublished":"2021-10-19T13:01:18+00:00","dateModified":"2026-03-05T07:56:41+00:00","description":"Dunkle Schokolade 80\u202f% aus Grenada, signiert von ORF\u00c8VE. Eine zart schmelzende Bean-to-Bar-Tafel mit Aromen von Banane und Pekannuss auf einem schokoladigen Hintergrund.","breadcrumb":{"@id":"https:\/\/orfeve.com\/de\/shop\/noir-de-noir\/tafel-dunkle-schookolade-esterre-80-grenada\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/orfeve.com\/de\/shop\/noir-de-noir\/tafel-dunkle-schookolade-esterre-80-grenada\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/orfeve.com\/de\/shop\/noir-de-noir\/tafel-dunkle-schookolade-esterre-80-grenada\/#primaryimage","url":"https:\/\/orfeve.com\/wp-content\/uploads\/2021\/10\/ORFEVE_Noir-de-Noir_chocolat_L-ESTERRE-80.jpg","contentUrl":"https:\/\/orfeve.com\/wp-content\/uploads\/2021\/10\/ORFEVE_Noir-de-Noir_chocolat_L-ESTERRE-80.jpg","width":900,"height":900},{"@type":"BreadcrumbList","@id":"https:\/\/orfeve.com\/de\/shop\/noir-de-noir\/tafel-dunkle-schookolade-esterre-80-grenada\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/orfeve.com\/de\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/orfeve.com\/de\/shop\/"},{"@type":"ListItem","position":3,"name":"L&#8217;Esterre 80 (Grenada) &#8211; Extrafeine Dunkle Schokolade"}]},{"@type":"WebSite","@id":"https:\/\/orfeve.com\/en\/#website","url":"https:\/\/orfeve.com\/en\/","name":"ORF\u00c8VE Chocolat suisse bean-to-bar","description":"Manufacture Suisse de Cacao et Chocolat Bean to Bar","publisher":{"@id":"https:\/\/orfeve.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/orfeve.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/orfeve.com\/en\/#organization","name":"ORF\u00c8VE","url":"https:\/\/orfeve.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/orfeve.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/orfeve.com\/wp-content\/uploads\/2021\/05\/Orfeve-Manufacture-Suisse-de-Cacao-et-Chocolat-logo.jpeg","contentUrl":"https:\/\/orfeve.com\/wp-content\/uploads\/2021\/05\/Orfeve-Manufacture-Suisse-de-Cacao-et-Chocolat-logo.jpeg","width":427,"height":170,"caption":"ORF\u00c8VE"},"image":{"@id":"https:\/\/orfeve.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/orfevechocolat\/","https:\/\/x.com\/orfeve_Chocolat","https:\/\/www.instagram.com\/orfeve_chocolat\/","https:\/\/www.linkedin.com\/company\/orfeve\/"]}]}},"_links":{"self":[{"href":"https:\/\/orfeve.com\/de\/wp-json\/wp\/v2\/product\/21464","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/orfeve.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/orfeve.com\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/orfeve.com\/de\/wp-json\/wp\/v2\/media\/25623"}],"wp:attachment":[{"href":"https:\/\/orfeve.com\/de\/wp-json\/wp\/v2\/media?parent=21464"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/orfeve.com\/de\/wp-json\/wp\/v2\/product_brand?post=21464"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/orfeve.com\/de\/wp-json\/wp\/v2\/product_cat?post=21464"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/orfeve.com\/de\/wp-json\/wp\/v2\/product_tag?post=21464"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}